{"id":2783,"date":"2023-06-26T22:20:28","date_gmt":"2023-06-26T22:20:28","guid":{"rendered":"https:\/\/herkesicinturizm.org\/kayit\/korumar-ephesus-hotel\/"},"modified":"2023-07-16T22:55:39","modified_gmt":"2023-07-16T22:55:39","slug":"korumar-ephesus-hotel","status":"publish","type":"kayit","link":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/","title":{"rendered":"Korumar Ephesus Hotel"},"content":{"rendered":"<p>Es ist ein wundersch\u00f6nes Meereshotel mit Haltegriffen in den Badezimmern und Toiletten f\u00fcr Behinderte, Rampen in den \u00dcbergangsbereichen und Poolaufz\u00fcgen. Nachfolgend finden Sie die Dienstleistungen des Hotels f\u00fcr Behinderte.<\/p>\n<p>Die direkt am Meer gelegene Anlage verf\u00fcgt \u00fcber einen gro\u00dfen Poolbereich und Aquapark-Optionen, die f\u00fcr Unterhaltung auf h\u00f6chstem Niveau sorgen. Das Anwesen zeichnet sich durch sein reichhaltiges Speise- und Getr\u00e4nkekonzept aus und bietet zus\u00e4tzlich zum Hauptrestaurant, das als offenes Buffet serviert, drei separate \u00c0-la-carte-Restaurants. In der Anlage, die den ganzen Tag \u00fcber viele Aktivit\u00e4tsm\u00f6glichkeiten bietet, werden auch abends Animationen organisiert. Spezielle Pflegebehandlungen und Massagem\u00f6glichkeiten werden im gro\u00dfen und gut ausgestatteten SPA-Center der Anlage angeboten, begleitet von einem erfahrenen Team. Im Miniclub der Anlage, der auch die Kinder nicht vergisst, werden in Begleitung erfahrener Animateure verschiedene Aktivit\u00e4ten durchgef\u00fchrt.<\/p>\n<p>Die direkt am Meer gelegene Anlage verf\u00fcgt \u00fcber einen 230 m langen Sandstrand. Liegen, Sonnenschirme und Handt\u00fccher am Strand sind kostenlos.<\/p>\n<p>Die Anlage in Selcuk; Es liegt 12 km vom Zentrum von Ku\u015fadas\u0131, 60 km vom Flughafen Izmir Adnan Menderes und 70 km vom Stadtzentrum von Izmir entfernt.<\/p>\n<h3>Transport<\/h3>\n<p>In der N\u00e4he der Anlage gibt es einen Kleinbus. Behindertenparkpl\u00e4tze stehen an der Unterkunft zur Verf\u00fcgung. Vom Flughafen\/Busbahnhof\/Bahnhof usw. Es gibt einen Transportservice zum Hotel.<\/p>\n<h3>Eingang zur Anlage<\/h3>\n<p>Der Name und das Logo der Einrichtung sind von au\u00dfen klar verst\u00e4ndlich. Vom Gartentor der Anlage bis zum Geb\u00e4udeeingang gibt es eine entsprechend dimensionierte Rampe. T\u00fcreing\u00e4nge sind entsprechend breit. Da es sich um eine Dreht\u00fcr handelt, besteht eine alternative, behindertengerechte Eingangst\u00fcr. Die T\u00fcr oder der T\u00fcrrahmen bilden einen optischen Kontrast zur Umgebung. Glast\u00fcren sind in entsprechender H\u00f6he mit Warnschildern gekennzeichnet. T\u00fcr \u00f6ffnet automatisch, wenn sie eine Person erkennt. Stufenloser Zugang zum Haupteingang ist m\u00f6glich. Blindenhunde sind gegen Geb\u00fchr erlaubt.<\/p>\n<h3>Eingang\/Lobby\/Rezeption<\/h3>\n<p>Korridore haben eine entsprechende Breite. Im Erdgeschoss der Anlage befindet sich eine Behindertentoilette in entsprechender Gr\u00f6\u00dfe mit Ruftaste. Die Eing\u00e4nge stehen optisch im Kontrast zur Umgebung. Es ist ausreichend Beleuchtung vorhanden. Die notwendigen Orientierungen an der Decke sind optisch kontrastreich und durchgehend einheitlich gro\u00df. Die Hauptdurchg\u00e4nge in den Fluren sind rollstuhlgerecht und die Flure sind rollstuhlgerecht. Die erste und letzte Sprosse haben eine kontrastierende Kante zu den horizontalen und vertikalen Sprossenfl\u00e4chen. Auf mindestens einer Seite der Stufen befindet sich ein Gel\u00e4nder. Am Anfang und Ende der Treppe setzen sich die Handl\u00e4ufe in entsprechenden Gr\u00f6\u00dfen fort. Am Anfang und Ende der Treppenstufen befindet sich eine Bodeninformation mit eingepr\u00e4gtem lateinischem Alphabet. Die Rampen in der Anlage entsprechen hinsichtlich Neigung, Breite und Bewegungsfl\u00e4che den geeigneten Kriterien. Am Start- und Endpunkt der Rampe sind ausreichend Bewegungsfl\u00e4chen vorhanden und die Rampe ist mit einem Anti-Rutsch versehen.<\/p>\n<h3>Aufzug<\/h3>\n<p>Es gibt keine Stufen, die zu einem H\u00f6henunterschied beim Erreichen des Aufzugs f\u00fchren k\u00f6nnten. Die Bewegungsfl\u00e4che vor dem Aufzug und der Kabine sind entsprechend dimensioniert. Notrufe im Aufzug k\u00f6nnen optisch erkannt werden. Es gibt ein Sprachansagesystem, das Ihnen mitteilt, welches Stockwerk erreicht wurde. Aufzugstasten sind in Blindenschrift beschriftet und gepr\u00e4gt. Bedienelemente und Schilder im Aufzug sind optisch kontrastreich gestaltet. In der Kabine befindet sich ein Standortschild, das anzeigt, in welcher Etage sich der Aufzug befindet.<\/p>\n<h3>Zimmer<\/h3>\n<p>Es gibt eine Wegbeschreibung zum Zimmer. Gr\u00f6\u00dfe und \u00d6ffnungsrichtung der Eingangst\u00fcr sind passend. Die Zimmernummer ist an der Wand rechts neben der T\u00fcr in Richtung T\u00fcrgriff angebracht. Das Zimmer und der Zimmerschl\u00fcssel\/die Zimmerkarte sind mit demselben Farbcode und\/oder Bildsymbol gekennzeichnet. Jeder Aspekt der Zimmerkarte kann genutzt werden. Die Durchgangsbreite in den R\u00e4umen ist rollstuhlgerecht (zwischen unbeweglichem Mobiliar und zugeh\u00f6rigen Wegen). Ein behindertengerechtes Doppelzimmer steht zur Verf\u00fcgung. F\u00fcr k\u00f6rperbehinderte Menschen k\u00f6nnen elektrische Betten gemietet werden. Im Behindertenzimmer gibt es auf beiden Seiten des Bettes eine geeignete Bewegungsfl\u00e4che. Am Bett befindet sich eine Ruftaste. Der Kleiderschrank ist behindertengerecht. Steckdosen, Lampen und Klimaanlage haben eine angemessene Gr\u00f6\u00dfe und die Steuerung der Klimaanlage ist zug\u00e4nglich. Informationsunterlagen stehen elektronisch zur Verf\u00fcgung. Duschgel, Fl\u00fcssigseife usw. Da die Produkte an der Wand montiert werden, sind sie f\u00fcr Sehbehinderte teilweise erkennbar. Der Balkon ist behindertengerecht und die Schwelle am Eingang kann mit einer Rampe begehbar gemacht werden. Visitenkarten mit der Adresse und Telefonnummer der Unterkunft liegen an der Rezeption oder im Schlafzimmer aus.<\/p>\n<h3>Toilette\/Bad<\/h3>\n<p>Die T\u00fcr \u00f6ffnet sich nach au\u00dfen. Die Breite der Badezimmert\u00fcr ist angemessen. Die Schwelle am Eingang ist 3 cm hoch. Es gibt eine Behindertentoilette. Die Bewegungsfl\u00e4che links oder rechts der Toilette ist entsprechend breit. Rechts und links an der Toilette befinden sich Griffe und an der Zugangsseite zur Toilette l\u00e4sst sie sich nach oben klappen. Die Waschtischfront hat eine ordentliche Gr\u00f6\u00dfe und die H\u00f6he ist f\u00fcr Rollstuhlfahrer geeignet. Der Spiegel ist im Stehen und Sitzen sichtbar. Es gibt keinen H\u00f6henunterschied zwischen dem Badezimmerboden und der Dusche. Die Bewegungsfl\u00e4che in der Dusche ist entsprechend gro\u00df und es gibt einen Duschstuhl. In der Dusche gibt es einen Griffbereich und einen Notrufknopf.<\/p>\n<h3>Soziale Verst\u00e4rkungsbereiche<\/h3>\n<p>In den Sozialr\u00e4umen der Einrichtung gibt es eine Behindertentoilette mit Rufknopf. Die Bewegungsfl\u00e4che vor der Theke in den Restaurants ist angemessen gro\u00df und die Tische befinden sich in einer rollstuhlgerechten H\u00f6he. Auf die Speisekarten kann per QR-Code zugegriffen werden. F\u00fcr Personen mit alternativen Ern\u00e4hrungsbed\u00fcrfnissen kann auf Anfrage ein Men\u00fc zusammengestellt werden. Der Zugang zu den \u00f6ffentlichen Bereichen erfolgt entweder flach oder \u00fcber eine Rampe.<\/p>\n<h3>Innenpool<\/h3>\n<p>Der Zugang zum Becken erfolgt im Sitzen und \u00fcber gerade Stufen mit Handl\u00e4ufen. Der Beckenrand bildet einen optischen Kontrast zur Umgebung. Es gibt einen Rettungsschwimmer.<\/p>\n<h3>Spa und Sauna<\/h3>\n<p>Der Zugang zu den Bereichen ist rollstuhlgerecht. Die Bewegungsfl\u00e4che vor der unteren Reihe der Sauna entspricht geeigneten Kriterien.<\/p>\n<h3>Offener Pool<\/h3>\n<p>Der Zugang zum Becken erfolgt \u00fcber gerade Stufen mit Handlauf und Treppen mit Handlauf. Der Beckenrand bildet einen optischen Kontrast zur Umgebung. Es gibt einen Rettungsschwimmer. Der Duschbereich bietet k\u00f6rperbehindertengerechte M\u00f6glichkeiten. Im Poolbereich gibt es eine Behindertentoilette.<\/p>\n<h3>Strandeinrichtungen<\/h3>\n<p>Es gibt eine Stra\u00dfe, die es Behinderten erm\u00f6glicht, den Zugang zum Meer zu erreichen. Am Strand gibt es spezielle Bereiche f\u00fcr Behinderte, die je nach Zimmernummer reserviert werden k\u00f6nnen. Vom Strand aus k\u00f6nnen Sie ins Meer gelangen. Behindertengerechte Strandk\u00f6rbe stehen zur Verf\u00fcgung. Am Strand gibt es eine Behindertentoilette. Es gibt einen Rettungsschwimmer. F\u00fcr die Sicherheit auf See stehen Bojen zur Verf\u00fcgung. Die Struktur des Strandes ist sandig und die Meerestiefe ist gering. In der Umkleidekabine steht ein Stuhl. Am Strand gibt es Bereiche wie barrierefreie Restaurants, Bars und Caf\u00e9s.<\/p>\n<h3>Konferenzraum<\/h3>\n<p>Es ist mit dem Aufzug erreichbar. Es gibt eine Behindertentoilette. Generell ist die Halle f\u00fcr orthop\u00e4disch behinderte Menschen geeignet. Die Halle ist ausreichend beleuchtet.<\/p>\n<h3>Ausstellungs- und Foyerbereiche<\/h3>\n<p>Ess- und Trinkst\u00e4nde sind barrierefrei zug\u00e4nglich. F\u00fcr Rollstuhlfahrer gibt es Cocktailtische in geeigneten Gr\u00f6\u00dfen.<\/p>\n<h3>Andere<\/h3>\n<p>Es werden allgemeine G\u00e4stebetreuungsschulungen durchgef\u00fchrt, die in regelm\u00e4\u00dfigen Abst\u00e4nden wiederholt werden. Der behinderte Mensch, der ins Hotel kommt, um das Hotel vorzustellen, erh\u00e4lt eine Orientierungshilfe. Veranstaltungen und Ank\u00fcndigungen der Einrichtung werden in Form von Sprachdurchsagen und Plakaten bekannt gegeben. Im Jahr 2022 wurden im Hotel behinderte G\u00e4ste untergebracht. Behinderte k\u00f6nnen entsprechend ihrer Behinderung spezielle Ausr\u00fcstung mieten. Die Anlage ist ein mit der Blauen Flagge ausgezeichnetes Hotel.<\/p>\n","protected":false},"featured_media":2517,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"kayit-kategori":[86,85],"class_list":["post-2783","kayit","type-kayit","status-publish","has-post-thumbnail","hentry","kayit-kategori-hotels-de","kayit-kategori-izmir-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Korumar Ephesus Hotel - Behindertengerechte Hotels - Tourismus f\u00fcr alle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Korumar Ephesus Hotel - Behindertengerechte Hotels - Tourismus f\u00fcr alle\" \/>\n<meta property=\"og:description\" content=\"Es ist ein wundersch\u00f6nes Meereshotel mit Haltegriffen in den Badezimmern und Toiletten f\u00fcr Behinderte, Rampen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/\" \/>\n<meta property=\"og:site_name\" content=\"Tourismus f\u00fcr alle\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-16T22:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/herkesicinturizm.org\/wp-content\/uploads\/engelliler-icin-uygun-oteller-korumar-ephesus-otel-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/kayit\\\/korumar-ephesus-hotel\\\/\",\"url\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/kayit\\\/korumar-ephesus-hotel\\\/\",\"name\":\"Korumar Ephesus Hotel - Behindertengerechte Hotels - Tourismus f\u00fcr alle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/kayit\\\/korumar-ephesus-hotel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/kayit\\\/korumar-ephesus-hotel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/herkesicinturizm.org\\\/wp-content\\\/uploads\\\/engelliler-icin-uygun-oteller-korumar-ephesus-otel-1.jpeg\",\"datePublished\":\"2023-06-26T22:20:28+00:00\",\"dateModified\":\"2023-07-16T22:55:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/kayit\\\/korumar-ephesus-hotel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/kayit\\\/korumar-ephesus-hotel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/kayit\\\/korumar-ephesus-hotel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/herkesicinturizm.org\\\/wp-content\\\/uploads\\\/engelliler-icin-uygun-oteller-korumar-ephesus-otel-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/herkesicinturizm.org\\\/wp-content\\\/uploads\\\/engelliler-icin-uygun-oteller-korumar-ephesus-otel-1.jpeg\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/kayit\\\/korumar-ephesus-hotel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Behindertengerechte Hotels\",\"item\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/aufzeichnung\\\/hotels-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Izmir\",\"item\":\"https:\\\/\\\/herkesicinturizm.org\\\/de\\\/aufzeichnung\\\/izmir-de\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Korumar Ephesus Hotel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/#website\",\"url\":\"https:\\\/\\\/herkesicinturizm.org\\\/\",\"name\":\"Tourismus f\u00fcr alle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/herkesicinturizm.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/#organization\",\"name\":\"Tourismus f\u00fcr alle\",\"url\":\"https:\\\/\\\/herkesicinturizm.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/herkesicinturizm.org\\\/wp-content\\\/uploads\\\/herkes-icin-turizm-dernegi-logo1.png\",\"contentUrl\":\"https:\\\/\\\/herkesicinturizm.org\\\/wp-content\\\/uploads\\\/herkes-icin-turizm-dernegi-logo1.png\",\"width\":125,\"height\":123,\"caption\":\"Tourismus f\u00fcr alle\"},\"image\":{\"@id\":\"https:\\\/\\\/herkesicinturizm.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Korumar Ephesus Hotel - Behindertengerechte Hotels - Tourismus f\u00fcr alle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/","og_locale":"de_DE","og_type":"article","og_title":"Korumar Ephesus Hotel - Behindertengerechte Hotels - Tourismus f\u00fcr alle","og_description":"Es ist ein wundersch\u00f6nes Meereshotel mit Haltegriffen in den Badezimmern und Toiletten f\u00fcr Behinderte, Rampen [&hellip;]","og_url":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/","og_site_name":"Tourismus f\u00fcr alle","article_modified_time":"2023-07-16T22:55:39+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/herkesicinturizm.org\/wp-content\/uploads\/engelliler-icin-uygun-oteller-korumar-ephesus-otel-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/","url":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/","name":"Korumar Ephesus Hotel - Behindertengerechte Hotels - Tourismus f\u00fcr alle","isPartOf":{"@id":"https:\/\/herkesicinturizm.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/#primaryimage"},"image":{"@id":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/#primaryimage"},"thumbnailUrl":"https:\/\/herkesicinturizm.org\/wp-content\/uploads\/engelliler-icin-uygun-oteller-korumar-ephesus-otel-1.jpeg","datePublished":"2023-06-26T22:20:28+00:00","dateModified":"2023-07-16T22:55:39+00:00","breadcrumb":{"@id":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/#primaryimage","url":"https:\/\/herkesicinturizm.org\/wp-content\/uploads\/engelliler-icin-uygun-oteller-korumar-ephesus-otel-1.jpeg","contentUrl":"https:\/\/herkesicinturizm.org\/wp-content\/uploads\/engelliler-icin-uygun-oteller-korumar-ephesus-otel-1.jpeg","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/herkesicinturizm.org\/de\/kayit\/korumar-ephesus-hotel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/herkesicinturizm.org\/de\/"},{"@type":"ListItem","position":2,"name":"Behindertengerechte Hotels","item":"https:\/\/herkesicinturizm.org\/de\/aufzeichnung\/hotels-de\/"},{"@type":"ListItem","position":3,"name":"Izmir","item":"https:\/\/herkesicinturizm.org\/de\/aufzeichnung\/izmir-de\/"},{"@type":"ListItem","position":4,"name":"Korumar Ephesus Hotel"}]},{"@type":"WebSite","@id":"https:\/\/herkesicinturizm.org\/#website","url":"https:\/\/herkesicinturizm.org\/","name":"Tourismus f\u00fcr alle","description":"","publisher":{"@id":"https:\/\/herkesicinturizm.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/herkesicinturizm.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/herkesicinturizm.org\/#organization","name":"Tourismus f\u00fcr alle","url":"https:\/\/herkesicinturizm.org\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/herkesicinturizm.org\/#\/schema\/logo\/image\/","url":"https:\/\/herkesicinturizm.org\/wp-content\/uploads\/herkes-icin-turizm-dernegi-logo1.png","contentUrl":"https:\/\/herkesicinturizm.org\/wp-content\/uploads\/herkes-icin-turizm-dernegi-logo1.png","width":125,"height":123,"caption":"Tourismus f\u00fcr alle"},"image":{"@id":"https:\/\/herkesicinturizm.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/herkesicinturizm.org\/de\/wp-json\/wp\/v2\/kayit\/2783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herkesicinturizm.org\/de\/wp-json\/wp\/v2\/kayit"}],"about":[{"href":"https:\/\/herkesicinturizm.org\/de\/wp-json\/wp\/v2\/types\/kayit"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herkesicinturizm.org\/de\/wp-json\/wp\/v2\/media\/2517"}],"wp:attachment":[{"href":"https:\/\/herkesicinturizm.org\/de\/wp-json\/wp\/v2\/media?parent=2783"}],"wp:term":[{"taxonomy":"kayit-kategori","embeddable":true,"href":"https:\/\/herkesicinturizm.org\/de\/wp-json\/wp\/v2\/kayit-kategori?post=2783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}